{"id":20279,"date":"2024-05-05T22:17:26","date_gmt":"2024-05-05T20:17:26","guid":{"rendered":"https:\/\/eltawkelstore.com\/?post_type=product&#038;p=20279"},"modified":"2025-09-26T11:23:05","modified_gmt":"2025-09-26T09:23:05","slug":"apple-pencil-2nd-generation","status":"publish","type":"product","link":"https:\/\/eltawkelstore.com\/en\/product\/apple-pencil-2nd-generation\/","title":{"rendered":"Apple Pencil (2nd generation)"},"content":{"rendered":"<table class=\"a-normal a-spacing-micro\">\n<tbody>\n<tr class=\"a-spacing-small po-color\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Color<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">White<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-brand\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Brand<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Apple<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-material\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Material<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Aluminum<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-num_batteries\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Number of Batteries<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">1 Lithium Polymer batteries required. (included)<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-item_weight\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Item Weight<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">0.73 Ounces<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-compatible_devices\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Compatible Devices<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">iPad<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-item_dimensions\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Item dimensions L x W x H<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">6.53 x 0.35 x 0.35 inches<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-batteries_included\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Are Batteries Included<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Yes<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-batteries_required\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Batteries Required?<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">Yes<\/span><\/td>\n<\/tr>\n<tr class=\"a-spacing-small po-item_diameter\">\n<td class=\"a-span3\"><span class=\"a-size-base a-text-bold\">Item Diameter<\/span><\/td>\n<td class=\"a-span9\"><span class=\"a-size-base po-break-word\">0.35 Inches<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Color White Brand Apple Material Aluminum Number of Batteries 1 Lithium Polymer batteries required. (included) Item Weight 0.73 Ounces Compatible<\/p>","protected":false},"featured_media":20280,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[49],"product_tag":[],"class_list":{"0":"post-20279","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-best-offers","8":"first","9":"outofstock","10":"sale","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/eltawkelstore.com\/en\/wp-json\/wp\/v2\/product\/20279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltawkelstore.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eltawkelstore.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/eltawkelstore.com\/en\/wp-json\/wp\/v2\/comments?post=20279"}],"version-history":[{"count":1,"href":"https:\/\/eltawkelstore.com\/en\/wp-json\/wp\/v2\/product\/20279\/revisions"}],"predecessor-version":[{"id":20282,"href":"https:\/\/eltawkelstore.com\/en\/wp-json\/wp\/v2\/product\/20279\/revisions\/20282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltawkelstore.com\/en\/wp-json\/wp\/v2\/media\/20280"}],"wp:attachment":[{"href":"https:\/\/eltawkelstore.com\/en\/wp-json\/wp\/v2\/media?parent=20279"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eltawkelstore.com\/en\/wp-json\/wp\/v2\/product_brand?post=20279"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eltawkelstore.com\/en\/wp-json\/wp\/v2\/product_cat?post=20279"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eltawkelstore.com\/en\/wp-json\/wp\/v2\/product_tag?post=20279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}